{"id":81840,"date":"2023-02-20T17:36:38","date_gmt":"2023-02-20T16:36:38","guid":{"rendered":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/?p=81840"},"modified":"2023-02-20T17:36:38","modified_gmt":"2023-02-20T16:36:38","slug":"evitaresfriadosentrenandoeninvierno","status":"publish","type":"post","link":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/triconsejos\/evitaresfriadosentrenandoeninvierno\/","title":{"rendered":"\u00bfC\u00f3mo evitar resfriarse cuando entrenamos en invierno?"},"content":{"rendered":"<h3><strong>Para entrenar al aire libre en invierno y no resfriarnos es necesario seguir una serie de consejos \u00a1Y no vale solo con abrigarse!<\/strong><\/h3>\n<p><a href=\"https:\/\/nutrisport.es\/geles\/37-energy-gel-taurina.html?utm_source=Triatletas+en+red&amp;utm_medium=Banner+revista+digital&amp;utm_campaign=Revista%3A+Triatletas+en+red\" rel=\"nofollow noopener\" target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-80108\" src=\"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-content\/uploads\/banner-geles.gif\" alt=\"\" width=\"750\" height=\"100\" \/><\/a><\/p>\n<p>Durante el invierno, la lluvia, el viento y las temperaturas bajas pueden hacer que salir a correr o montar en bici al aire libre se convierta en una misi\u00f3n imposible. Pero esto tiene f\u00e1cil soluci\u00f3n, y aqu\u00ed te dejamos algunos consejos para que puedas cuidar tu salud y comenzar a entrenar sin ning\u00fan tipo de riesgo.<\/p>\n<p>Durante el invierno, es particularmente complicado para los deportistas, y en particular los triatletas al entrenar en exterior, evitar una gripe, ya que somos m\u00e1s propensos a caer enfermos si abusamos de los entrenamientos. Sin embargo. el ejercicio puede ser un gran aliado para prevenir y reducir el tiempo que estamos costipados, solo debes aprender a cuidarte y reforzar tus sistema inmune para que no tengas que perder muchos d\u00edas de entrenamiento.<\/p>\n<p>Algo a favor de los deportistas es que tenemos un sistema inmune m\u00e1s fuerte y nos recuperamos antes de algunas enfermedades, as\u00ed que no hay motivos para remolonear en casa. Incluso, realizando ejercicio suave se puede prevenir y tambi\u00e9n curar cualquier infecci\u00f3n.<\/p>\n<h3><strong>Usa la t\u00e9cnica de la cebolla.<\/strong><\/h3>\n<p>Lo primero que debes hacer es elegir bien la ropa para entrenar. Utiliza prendas de abrigo t\u00e9cnicas como camisetas t\u00e9rmicas de calidad que conserven el calor corporal y eliminen el sudor para que la ropa siempre est\u00e9 seca. Adem\u00e1s, es recomendable llevar varias capas de ropa para aislar el cuerpo e ir pudi\u00e9ndonoslas quitar a medida que vaya aumentando nuestra temperatura corporal, la famosa t\u00e9cnica de la cebolla.<\/p>\n<h3><strong>Mejora tu sistema inmune<\/strong><\/h3>\n<p>Para reforzar tu sistema inmune, come alimentos ricos en antioxidantes como frutas, verduras, frutos secos, aceite de oliva virgen extra o huevos. Las vitaminas A, C y E, as\u00ed como los minerales como el selenio y el zinc, ayudan a mantener fuerte el sistema inmune ayudando a combatir virus e infecciones.<\/p>\n<p>Si consideras que ya sigues una alimentaci\u00f3n equilibrada y rica en estos minerales y vitaminas, siempre puedes a\u00f1adir un extra al tomar suplementos vitam\u00ednicos o aislados de algunas vitaminas que tengas mas carencias. En especial la Vitamina C y D son las mas importantes a la hora de suplementar.<\/p>\n<h3><strong>Otros h\u00e1bitos saludables<\/strong><\/h3>\n<p>Adem\u00e1s de lo anterior, es fundamental llevar unos h\u00e1bitos de vida saludables (adem\u00e1s de hacer deporte) y que muchas veces no prestamos tanta atenci\u00f3n. Dormir al menos 7 horas al d\u00eda, beber mucha agua y comer alimentos saludables como los cereales integrales, pescado y alimentos de temporada son detalles fundamentales que tambi\u00e9n nos prevendr\u00e1n de muchos virus e infecciones.<\/p>\n<p><span class=\"td_btn td_btn_lg td_outlined_btn\"><a href=\"https:\/\/nutrisport.es\/49-vitaminas-minerales-y-antioxidantes\" rel=\"nofollow noopener\" target=\"_blank\">SUPLEMENTOS QUE PUEDEN AYUDARTE<\/a><\/span><\/p>\n<div class=\"youtube-embed\" data-video_id=\"_Poq0sxFgpU\"><iframe title=\"\ud83d\udca5 CHALLENGE BARCELONA, ser\u00e1 una REALIDAD \ud83d\udca5 | Todos los detalles aqu\u00ed\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/_Poq0sxFgpU?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Para entrenar al aire libre en invierno y no resfriarnos es necesario seguir una serie de consejos \u00a1Y no vale solo con abrigarse!<\/p>\n","protected":false},"author":322,"featured_media":81841,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[5675],"tags":[],"class_list":{"0":"post-81840","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-triconsejos"},"acf":[],"_links":{"self":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts\/81840"}],"collection":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/users\/322"}],"replies":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/comments?post=81840"}],"version-history":[{"count":1,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts\/81840\/revisions"}],"predecessor-version":[{"id":81842,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts\/81840\/revisions\/81842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/media\/81841"}],"wp:attachment":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/media?parent=81840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/categories?post=81840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/tags?post=81840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}