{"id":6715,"date":"2012-12-18T06:13:46","date_gmt":"2012-12-18T06:13:46","guid":{"rendered":"http:\/\/triatletasenred.com\/?p=6715"},"modified":"2012-12-24T07:37:10","modified_gmt":"2012-12-24T07:37:10","slug":"proximos-eventos-running-solutions","status":"publish","type":"post","link":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/competiciones\/proximos-eventos-running-solutions\/","title":{"rendered":"Pr\u00f3ximos eventos Running Solutions"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>4a Mitja Marat\u00f3 de Cambrils<\/strong><\/p>\n<p style=\"text-align: justify;\">Llega la tercera prueba de las <a href=\"http:\/\/t.ymlp287.net\/ymbagahqwyataushaoauuwbe\/click.php\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Runnersworld Tarragona Half Marathon Series by SPORT<\/strong><\/a>. Si ya participaste en la <strong>Mitja del Vendrell y Salou<\/strong>, sigue compitiendo en las HMS inscribi\u00e9ndote a la <a href=\"http:\/\/t.ymlp287.net\/ymhaoahqwyaiaushagauuwbe\/click.php\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Mitja de Cambrils<\/strong><\/a> \u201cposiblemente la mitja m\u00e1s r\u00e1pida\u201d.<span style=\"text-align: center;\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter\" title=\"mitja cambrils\" src=\"http:\/\/www.mitjadecambrils.com\/imagenes\/foto_index10.jpg\" alt=\"\" width=\"415\" height=\"277\" \/><\/p>\n<p style=\"text-align: justify;\">No dejes la oportunidad de poder correr en esta nueva edici\u00f3n de la Mitja de Cambrils y los 10K.<\/p>\n<p style=\"text-align: justify;\"><strong>El pr\u00f3ximo lunes d\u00eda 17 de diciembre abrimos inscripciones y s\u00f3lo durante 24h puedes inscribirte a un precio s\u00faper reducido.<\/strong><\/p>\n<p><strong><a href=\"http:\/\/t.ymlp287.net\/ymwalahqwyaraushavauuwbe\/click.php\" rel=\"nofollow noopener\" target=\"_blank\">www.mitjadecambrils.com<\/a><\/strong><\/p>\n<p><strong>2a San Silvestre Vendrell<\/strong><\/p>\n<p style=\"text-align: justify;\">La <a href=\"http:\/\/t.ymlp287.net\/ymqagahqwyakaushaaauuwbe\/click.php\" rel=\"nofollow noopener\" target=\"_blank\"><strong>II San Silvestre del Vendrell<\/strong><\/a>, un nuevo circuito de 5k, r\u00e1pido y a pie de mar que contar\u00e1 con la presencia del campe\u00f3n de Espa\u00f1a y de la pasada BB\/SS <strong>Jaume Leiva<\/strong>.<span style=\"text-align: center;\">\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter\" title=\"sant silvestre vendrell\" src=\"http:\/\/www.sansilvestrevendrell.com\/imagenes\/cabecera.gif\" alt=\"\" width=\"429\" height=\"253\" \/><\/p>\n<p style=\"text-align: justify;\">Ap\u00fantate y ll\u00e9vate un original y diferente regalo (polar de cuello + guantes) para que no pases fr\u00edo en tus entrenos.<\/p>\n<p><strong><a href=\"http:\/\/t.ymlp287.net\/ymyaaahqwyacaushaoauuwbe\/click.php\" rel=\"nofollow noopener\" target=\"_blank\">www.sansilvestrevendrell.com<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>10K Correndo por Vigo 2013<\/strong><\/p>\n<p style=\"text-align: justify;\">Ya puedes apuntarte a la II edici\u00f3n de los <a href=\"http:\/\/t.ymlp287.net\/yjsarahqwyapaushagauuwbe\/click.php\" rel=\"nofollow noopener\" target=\"_blank\"><strong>10k Correndo por Vigo<\/strong><\/a>, que se celebrar\u00e1 el pr\u00f3ximo 13 de Enero a las 11h en la que podemos disfrutar de la compa\u00f1\u00ed\u00eda de <strong>Mart\u00edn Fiz<\/strong>. Se trata de una bonita carrera que abre el calendario del running Gallego 2013.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"aligncenter\" title=\"10k vigo\" src=\"http:\/\/www.correndoporvigo.hol.es\/images\/content_slide1.jpg\" alt=\"\" width=\"431\" height=\"210\" \/><\/p>\n<p style=\"text-align: justify;\">El d\u00eda 12 por la tarde, tendr\u00e1 lugar una gratuita y apasionante mesa redonda con pasado y futuro del fondo nacional, que no te puedes perder con dos campeones nacionales, <strong>Mart\u00edn Fiz y Jaume Leiva<\/strong>.<\/p>\n<p style=\"text-align: justify;\">La mesa estar\u00e1 moderada por <strong>Juanan Fern\u00e1ndez<\/strong> que volver\u00e1 a ser el Speaker oficial de la <a href=\"http:\/\/t.ymlp287.net\/yjsarahqwyapaushagauuwbe\/click.php\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Correndo por VIGO 2013.<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\"><strong><a href=\"http:\/\/t.ymlp287.net\/yjsarahqwyapaushagauuwbe\/click.php\" rel=\"nofollow noopener\" target=\"_blank\">www.correndoporvigo.hol.es<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Marat\u00f3 Costa Daurada Tarrgona 2017<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Running Solutions<\/strong> y <strong>Tarragona 2017<\/strong> presenta la <a href=\"http:\/\/t.ymlp287.net\/yjuavahqwyaaaushafauuwbe\/click.php\" rel=\"nofollow noopener\" target=\"_blank\"><strong>Marat\u00f3 Costa Daurada Tarragona 2017<\/strong><\/a>. Que ser\u00e1 la primera marat\u00f3n que se celebrar\u00e1 en Tarragona ciudad.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"mcd\" src=\"https:\/\/dl.dropbox.com\/u\/3879676\/triATLETAS\/imatges\/competis\/marato%20tarragona\/mcd13.jpg\" alt=\"\" width=\"450\" height=\"176\" \/><\/p>\n<p style=\"text-align: justify;\">Una atractiva Marat\u00f3n con salida y llegada en el Port de Tarragona. Un circuito \u00fanico pasando los primeros kil\u00f3metros por el litoral as\u00ed como acerc\u00e1ndose a los barrios de Ponent y Llevant.<\/p>\n<p style=\"text-align: justify;\">Conjuntamente con la MCD Tarragona 2017 podr\u00e1s disfrutar de un 10K r\u00e1pido y llano con solo dos giros y pegado al mar. El pr\u00f3ximo d\u00eda 20 de Enero os esperamos.<\/p>\n<p style=\"text-align: justify;\"><strong>Si no te atreves con los 42k puedes hacer los 10K<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/t.ymlp287.net\/yjuavahqwyaaaushafauuwbe\/click.php\" rel=\"nofollow noopener\" target=\"_blank\"><strong>www.maratocostadauradatarragona2017.com<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>4a Mitja Marat\u00f3 de Cambrils Llega la tercera prueba de las Runnersworld Tarragona Half Marathon Series by SPORT. Si ya participaste en la Mitja del Vendrell y Salou, sigue compitiendo en las HMS inscribi\u00e9ndote a la Mitja de Cambrils \u201cposiblemente la mitja m\u00e1s r\u00e1pida\u201d.\u00a0 No dejes la oportunidad de poder correr en esta nueva edici\u00f3n [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":6716,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[19],"tags":[138,421],"class_list":{"0":"post-6715","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-competiciones","8":"tag-running","9":"tag-running-solutions"},"acf":[],"_links":{"self":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts\/6715"}],"collection":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/comments?post=6715"}],"version-history":[{"count":0,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts\/6715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/media\/6716"}],"wp:attachment":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/media?parent=6715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/categories?post=6715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/tags?post=6715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}