{"id":60694,"date":"2019-01-28T06:58:03","date_gmt":"2019-01-28T04:58:03","guid":{"rendered":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/?p=60694"},"modified":"2019-01-28T17:58:08","modified_gmt":"2019-01-28T15:58:08","slug":"ultimos-dias-de-precio-reducido-en-la-copa-catalana-olympic","status":"publish","type":"post","link":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/actualidad\/ultimos-dias-de-precio-reducido-en-la-copa-catalana-olympic\/","title":{"rendered":"\u00daltimos d\u00edas de precio reducido en la Copa Catalana Olympic"},"content":{"rendered":"<h3 style=\"text-align: justify;\"><strong>El triatl\u00f3n catal\u00e1n tiene este a\u00f1o un gran atractivo con las Copas Catalanas Olympic y Half. Un aliciente m\u00e1s para no perder de vista las pruebas de 100% Tri y 100% Half.<\/strong><\/h3>\n<p><a href=\"http:\/\/triatlondesevilla.com\/?utm_source=trisevilla19&amp;utm_medium=trienred\" rel=\"nofollow noopener\" target=\"_blank\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-59989\" src=\"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-content\/uploads\/Banner_TRI_SEV_700x150_01.jpg\" alt=\"\" width=\"700\" height=\"150\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">El triatl\u00f3n catal\u00e1n sigue dando muestras de estar en un estado de salud envidiable. Actualmente es sin duda, una de las comunidades aut\u00f3nomas con m\u00e1s triatletas federados y con mayor n\u00famero de pruebas. Buena fe de este gran estado de salud pueden dar los siete triatlones correspondientes a los proyectos <strong>100% Half y 100% Tri<\/strong>, donde a\u00f1o tras a\u00f1o siguen batiendo records.<\/p>\n<p style=\"text-align: justify;\">Centr\u00e1ndonos en las pruebas de <strong>distancia ol\u00edmpica<\/strong>, que es lo que abarca este art\u00edculo, para las ediciones correspondientes a este a\u00f1o se ha creado la<strong> Copa Catalana<\/strong>. Un formato de competici\u00f3n por puntos en el que existen premios individuales y por grupos de edad (econ\u00f3micos y materiales).<\/p>\n<p style=\"text-align: justify;\">Para poder optar a la clasificaci\u00f3n general de la <strong>Copa Catalana Olympic<\/strong>, hay que competir en al menos tres de los cuatro triatlones que componen 100% Tri. Dichas pruebas tendr\u00e1n lugar en las localidades de <strong>Platja d\u2019Aro, Ametlla de Mar, Empuriabrava y l\u2019Estartit<\/strong>. Para obtener m\u00e1s informaci\u00f3n sobre las mismas, pod\u00e9is acceder a <a href=\"https:\/\/100x100tri.com\/tri\/\" rel=\"nofollow noopener\" target=\"_blank\">su web<\/a>.<\/p>\n<p style=\"text-align: justify;\">Actualmente, existe un pack de inscripciones para las cuatro pruebas que conforman dicha Copa Catalana. A d\u00eda de hoy, os pod\u00e9is hacer con este paquete por un precio m\u00e1s que asequible de <strong>138,75\u20ac<\/strong>. Pero, este precio se mantendr\u00e1 solo hasta este mismo jueves d\u00eda 31, a partir de dicha fecha dejar\u00e1 de ser efectivo el 15% de descuento que se ven\u00eda aplicando.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/100x100tri.com\/estartit\/copa-catalana-olympic\/\" rel=\"nofollow noopener\" target=\"_blank\">Si hac\u00e9is click aqu\u00ed<\/a>\u00a0encontrar\u00e9is m\u00e1s informaci\u00f3n correspondiente a dicha competici\u00f3n, sus precios y reglamento. \u00a1Nos vemos en la Copa Catalana Olympic 2019!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El triatl\u00f3n catal\u00e1n tiene este a\u00f1o un gran atractivo con las Copas Catalanas Olympic y Half. Un aliciente m\u00e1s para no perder de vista las pruebas de 100% Tri y 100% Half. El triatl\u00f3n catal\u00e1n sigue dando muestras de estar en un estado de salud envidiable. Actualmente es sin duda, una de las comunidades aut\u00f3nomas [&hellip;]<\/p>\n","protected":false},"author":302,"featured_media":60699,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[17,19,1191],"tags":[6394],"class_list":{"0":"post-60694","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"category-competiciones","9":"category-triatlon","10":"tag-copa-catalana-olympic"},"acf":[],"_links":{"self":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts\/60694"}],"collection":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/users\/302"}],"replies":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/comments?post=60694"}],"version-history":[{"count":0,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts\/60694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/media\/60699"}],"wp:attachment":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/media?parent=60694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/categories?post=60694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/tags?post=60694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}