{"id":60422,"date":"2019-01-10T06:58:49","date_gmt":"2019-01-10T04:58:49","guid":{"rendered":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/?p=60422"},"modified":"2019-01-10T01:17:03","modified_gmt":"2019-01-09T23:17:03","slug":"la-temporada-ironman-2019-arranca-con-el-70-3-de-pucon","status":"publish","type":"post","link":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/actualidad\/la-temporada-ironman-2019-arranca-con-el-70-3-de-pucon\/","title":{"rendered":"La temporada Ironman 2019 arranca con el 70.3 de Puc\u00f3n"},"content":{"rendered":"<h3 style=\"text-align: justify;\">La ciudad chilena acoge el domingo la 1\u00aa prueba Ironman de la temporada con Andy Potts y B\u00e1rbara Riveros como principales favoritos a la victoria.<\/h3>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-59129\" src=\"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-content\/uploads\/MOLA_700X150_estatica.jpg\" alt=\"\" width=\"700\" height=\"150\" srcset=\"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-content\/uploads\/MOLA_700X150_estatica.jpg 700w, https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-content\/uploads\/MOLA_700X150_estatica-300x64.jpg 300w, https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-content\/uploads\/MOLA_700X150_estatica-640x137.jpg 640w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p>\n<p style=\"text-align: justify;\">Estamos en la segunda semana de enero pero la temporada de triatl\u00f3n internacional se prepara para el disparo de salida. La primera prueba destacada del calendario 2019 ser\u00e1 el<strong> Ironman 70.3 de Puc\u00f3n<\/strong>, que celebrar\u00e1 el pr\u00f3ximo domingo su 31\u00aa edici\u00f3n. La carrera dar\u00e1 comienzo a partir de las 7.45 AM (hora local) con un segmento de nataci\u00f3n de 1.900 metros en el lago cercano al <strong>volc\u00e1n Villarica.<\/strong><\/p>\n<p style=\"text-align: justify;\">Tras la victoria en 2018 de<strong> Lionel Sanders, Andy Potts<\/strong> figura en la lista masculina de profesionales como el principal candidato a la victoria. Para lograr el triunfo, el estadounidense de 42 a\u00f1os tendr\u00e1 que superar a un amplio listado de triatletas sudamericanos. Respecto a la prueba femenina, <strong>B\u00e1rbara Riveros<\/strong> intentar\u00e1 llevarse su 5\u00aa victoria en este 70.3 de Puc\u00f3n. La chilena, que actualmente es la \u00fanica deportista del mundo que puede decir que est\u00e1 clasificada tanto para<strong> Kona 2019<\/strong> como para los<strong> JJOO de 2020<\/strong> (a d\u00eda de hoy es 34\u00aa en el r\u00e1nking ITU), tendr\u00e1 como rivales a las estadounidenses <strong>Linsey Corbin y Alicia Kaye.\u00a0<\/strong><\/p>\n<div class=\"youtube-embed\" data-video_id=\"X1zDbylPQao\"><iframe title=\"HERBALIFE NUTRITION PUCON CHILE 2019\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/X1zDbylPQao?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La ciudad chilena acoge el domingo la 1\u00aa prueba Ironman de la temporada con Andy Potts y B\u00e1rbara Riveros como principales favoritos a la victoria.<\/p>\n","protected":false},"author":302,"featured_media":60424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"rank_math_lock_modified_date":false,"footnotes":""},"categories":[17,2033],"tags":[5065,6469,2980,5178],"class_list":{"0":"post-60422","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"category-sport","9":"tag-andy-potts","10":"tag-barbara-riveros","11":"tag-ironman-70-3-pucon","12":"tag-lionel-sanders"},"acf":[],"_links":{"self":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts\/60422"}],"collection":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/users\/302"}],"replies":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/comments?post=60422"}],"version-history":[{"count":0,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/posts\/60422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/media\/60424"}],"wp:attachment":[{"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/media?parent=60422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/categories?post=60422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/miurltemporal.com/main/triatletasenred.sport.es\/wp-json\/wp\/v2\/tags?post=60422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}